{"id":390,"date":"2026-02-12T18:14:02","date_gmt":"2026-02-12T17:14:02","guid":{"rendered":"https:\/\/www.agrifoodporttarragona.com\/?page_id=390"},"modified":"2026-03-27T11:42:12","modified_gmt":"2026-03-27T10:42:12","slug":"inicio","status":"publish","type":"page","link":"https:\/\/www.agrifoodporttarragona.com\/es\/","title":{"rendered":"Inicio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"390\" class=\"elementor elementor-390 elementor-14\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d64e44 e-flex e-con-boxed e-con e-parent\" data-id=\"2d64e44\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-dd78639 e-con-full e-flex e-con e-child\" data-id=\"dd78639\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d24491 elementor-widget elementor-widget-heading\" data-id=\"9d24491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Salutaci\u00f3n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e1a624 elementor-widget elementor-widget-heading\" data-id=\"9e1a624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Una gran oportunidad para preparar el futuro compartiendo ideas y propuestas<\/div>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c227a52 elementor-widget elementor-widget-text-editor\" data-id=\"c227a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Port Tarragona <\/strong>presenta el <strong>5<sup>th<\/sup>\u00a0Agrifood International Congress<\/strong>, que tendr\u00e1 lugar los d\u00edas <strong>15 y 16 de octubre de 2026<\/strong> y que, como en ediciones anteriores, pretende ser el foro de intercambio de conocimientos e informaci\u00f3n m\u00e1s importante del sector en el sur de Europa.<\/p><p>En el programa que hemos preparado para este a\u00f1o, dedicaremos una atenci\u00f3n especial a la resiliencia del sistema agroalimentario frente a entornos cada vez m\u00e1s complejos, vol\u00e1tiles e inciertos. Asimismo, de la mano de los mejores expertos, abordaremos algunos de los grandes equilibrios que hoy condicionan la toma de decisiones en el sector: la relaci\u00f3n entre seguridad de suministro y eficiencia de costes, entre sostenibilidad y competitividad, as\u00ed como la coherencia entre los objetivos estrat\u00e9gicos declarados y las decisiones operativas que se adoptan en la pr\u00e1ctica.<\/p><p>Este programa lo complementamos dedicando tiempo al intercambio de informaci\u00f3n y al networking entre todos los actores que forman parte de esta comunidad, ya que es importante ampliar el intercambio personal para fomentar tambi\u00e9n los negocios y el crecimiento del sector.<\/p><p>Este <strong>5th Agrifood International Congress<\/strong> sigue siendo una gran oportunidad para preparar el futuro compartiendo ideas y propuestas, aprovechando el marco que ofrece el <strong>Puerto de Tarragona, el puerto l\u00edder del sector agroalimentario en el Mediterr\u00e1neo.<\/strong><\/p><p>Esperamos contar con vuestra presencia activa en este congreso para, entre todos, conseguir que sea lo m\u00e1s enriquecedor posible. Por nuestra parte, haremos todos los esfuerzos para que as\u00ed sea.<\/p><p>\u00a1Os esperamos!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2c3cb7 e-con-full e-flex e-con e-child\" data-id=\"d2c3cb7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;sticky_offset_tablet&quot;:20,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;sticky_offset&quot;:0,&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7c6343c elementor-widget elementor-widget-image\" data-id=\"7c6343c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1854\" height=\"2560\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/03\/foto_president_opuscle2025-2-scaled.jpg\" class=\"attachment-large size-large wp-image-981\" alt=\"\" srcset=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/03\/foto_president_opuscle2025-2-scaled.jpg 1854w, https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/03\/foto_president_opuscle2025-2-768x1060.jpg 768w, https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/03\/foto_president_opuscle2025-2-1112x1536.jpg 1112w, https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/03\/foto_president_opuscle2025-2-1483x2048.jpg 1483w\" sizes=\"(max-width: 1854px) 100vw, 1854px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-816d0b1 elementor-widget elementor-widget-text-editor\" data-id=\"816d0b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><strong>Santiago J. Castell\u00e0<\/strong><br \/>Presidente de Port Tarragona<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-865737c e-flex e-con-boxed e-con e-parent\" data-id=\"865737c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6887f36 elementor-widget elementor-widget-heading\" data-id=\"6887f36\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Razones para asistir<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6d986e1 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"6d986e1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">\u00bfPor qu\u00e9 deber\u00edas asistir al 5<sup>th<\/sup> International Agrifood Congress 2026?<\/div>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2908374 e-grid e-con-full e-con e-child\" data-id=\"2908374\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b01702b elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"b01702b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-edit\" viewBox=\"0 0 576 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M402.3 344.9l32-32c5-5 13.7-1.5 13.7 5.7V464c0 26.5-21.5 48-48 48H48c-26.5 0-48-21.5-48-48V112c0-26.5 21.5-48 48-48h273.5c7.1 0 10.7 8.6 5.7 13.7l-32 32c-1.5 1.5-3.5 2.3-5.7 2.3H48v352h352V350.5c0-2.1.8-4.1 2.3-5.6zm156.6-201.8L296.3 405.7l-90.4 10c-26.2 2.9-48.5-19.2-45.6-45.6l10-90.4L432.9 17.1c22.9-22.9 59.9-22.9 82.7 0l43.2 43.2c22.9 22.9 22.9 60 .1 82.8zM460.1 174L402 115.9 216.2 301.8l-7.3 65.3 65.3-7.3L460.1 174zm64.8-79.7l-43.2-43.2c-4.1-4.1-10.8-4.1-14.8 0L436 82l58.1 58.1 30.9-30.9c4-4.2 4-10.8-.1-14.9z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAnaliza los cambios estructurales que est\u00e1n redefiniendo el comercio internacional de materias primas agroalimentarias, de la mano de expertos de referencia del \u00e1mbito econ\u00f3mico, log\u00edstico y sectorial. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c6c7459 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"c6c7459\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-lightbulb\" viewBox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M176 80c-52.94 0-96 43.06-96 96 0 8.84 7.16 16 16 16s16-7.16 16-16c0-35.3 28.72-64 64-64 8.84 0 16-7.16 16-16s-7.16-16-16-16zM96.06 459.17c0 3.15.93 6.22 2.68 8.84l24.51 36.84c2.97 4.46 7.97 7.14 13.32 7.14h78.85c5.36 0 10.36-2.68 13.32-7.14l24.51-36.84c1.74-2.62 2.67-5.7 2.68-8.84l.05-43.18H96.02l.04 43.18zM176 0C73.72 0 0 82.97 0 176c0 44.37 16.45 84.85 43.56 115.78 16.64 18.99 42.74 58.8 52.42 92.16v.06h48v-.12c-.01-4.77-.72-9.51-2.15-14.07-5.59-17.81-22.82-64.77-62.17-109.67-20.54-23.43-31.52-53.15-31.61-84.14-.2-73.64 59.67-128 127.95-128 70.58 0 128 57.42 128 128 0 30.97-11.24 60.85-31.65 84.14-39.11 44.61-56.42 91.47-62.1 109.46a47.507 47.507 0 0 0-2.22 14.3v.1h48v-.05c9.68-33.37 35.78-73.18 52.42-92.16C335.55 260.85 352 220.37 352 176 352 78.8 273.2 0 176 0z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tReflexiona sobre la resiliencia del sistema agroalimentario y los principales equilibrios que condicionan su evoluci\u00f3n, as\u00ed como sobre los retos clave de la cadena log\u00edstica, desde el abastecimiento internacional hasta el transporte mar\u00edtimo, los puertos y la log\u00edstica terrestre. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5386fcb elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"5386fcb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-globe\" viewBox=\"0 0 496 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M336.5 160C322 70.7 287.8 8 248 8s-74 62.7-88.5 152h177zM152 256c0 22.2 1.2 43.5 3.3 64h185.3c2.1-20.5 3.3-41.8 3.3-64s-1.2-43.5-3.3-64H155.3c-2.1 20.5-3.3 41.8-3.3 64zm324.7-96c-28.6-67.9-86.5-120.4-158-141.6 24.4 33.8 41.2 84.7 50 141.6h108zM177.2 18.4C105.8 39.6 47.8 92.1 19.3 160h108c8.7-56.9 25.5-107.8 49.9-141.6zM487.4 192H372.7c2.1 21 3.3 42.5 3.3 64s-1.2 43-3.3 64h114.6c5.5-20.5 8.6-41.8 8.6-64s-3.1-43.5-8.5-64zM120 256c0-21.5 1.2-43 3.3-64H8.6C3.2 212.5 0 233.8 0 256s3.2 43.5 8.6 64h114.6c-2-21-3.2-42.5-3.2-64zm39.5 96c14.5 89.3 48.7 152 88.5 152s74-62.7 88.5-152h-177zm159.3 141.6c71.4-21.2 129.4-73.7 158-141.6h-108c-8.8 56.9-25.6 107.8-50 141.6zM19.3 352c28.6 67.9 86.5 120.4 158 141.6-24.4-33.8-41.2-84.7-50-141.6h-108z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tComprende el impacto de las tensiones geopol\u00edticas, la reconfiguraci\u00f3n de los mercados y las nuevas normativas europeas en la competitividad del sector y en la toma de decisiones empresariales. \t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4dcb279 elementor-position-inline-start elementor-view-default elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"4dcb279\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-network-wired\" viewBox=\"0 0 640 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M640 264v-16c0-8.84-7.16-16-16-16H344v-40h72c17.67 0 32-14.33 32-32V32c0-17.67-14.33-32-32-32H224c-17.67 0-32 14.33-32 32v128c0 17.67 14.33 32 32 32h72v40H16c-8.84 0-16 7.16-16 16v16c0 8.84 7.16 16 16 16h104v40H64c-17.67 0-32 14.33-32 32v128c0 17.67 14.33 32 32 32h160c17.67 0 32-14.33 32-32V352c0-17.67-14.33-32-32-32h-56v-40h304v40h-56c-17.67 0-32 14.33-32 32v128c0 17.67 14.33 32 32 32h160c17.67 0 32-14.33 32-32V352c0-17.67-14.33-32-32-32h-56v-40h104c8.84 0 16-7.16 16-16zM256 128V64h128v64H256zm-64 320H96v-64h96v64zm352 0h-96v-64h96v64z\"><\/path><\/svg>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tAmpl\u00eda tu red de contactos en espacios de networking de alto nivel, conectando con los principales decisores del sector y generando nuevas oportunidades de colaboraci\u00f3n.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0bcb537 e-flex e-con-boxed e-con e-parent\" data-id=\"0bcb537\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-723f25d elementor-widget elementor-widget-heading\" data-id=\"723f25d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Informaci\u00f3n del programa<\/h2>\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36ea43e e-grid e-con-full e-con e-child\" data-id=\"36ea43e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-559a996 elementor-cta--layout-image-above elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"559a996\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_04.png);\" role=\"img\" aria-label=\"slider_04\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPrograma del Congreso\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tTodos los detalles e informaci\u00f3n completa de las conferencias programadas, horarios y ponentes del 5th International Agrifood Congress. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.agrifoodporttarragona.com\/es\/el-congreso\/#programa\">\n\t\t\t\t\t\tAcceder al Programa.\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe1879f elementor-cta--layout-image-above elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-cta--skin-classic elementor-animated-content elementor-bg-transform elementor-bg-transform-zoom-in elementor-widget elementor-widget-call-to-action\" data-id=\"fe1879f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"call-to-action.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-cta\">\n\t\t\t\t\t<div class=\"elementor-cta__bg-wrapper\">\n\t\t\t\t<div class=\"elementor-cta__bg elementor-bg\" style=\"background-image: url(https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/img_card_02.png);\" role=\"img\" aria-label=\"img_card_02\"><\/div>\n\t\t\t\t<div class=\"elementor-cta__bg-overlay\"><\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-cta__content\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-cta__title elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tPonentes\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__description elementor-cta__content-item elementor-content-item\">\n\t\t\t\t\t\tConoce de primera mano todas las novedades del sector. Grandes profesionales con amplia experiencia. Ellos son los ponentes del 5th International Agrifood Congress. \t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-cta__button-wrapper elementor-cta__content-item elementor-content-item \">\n\t\t\t\t\t<a class=\"elementor-cta__button elementor-button elementor-size-\" href=\"https:\/\/www.agrifoodporttarragona.com\/es\/el-congreso\/#ponentes\">\n\t\t\t\t\t\tSaber m\u00e1s\t\t\t\t\t<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c39577e elementor-widget elementor-widget-heading\" data-id=\"c39577e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">EDICIONES ANTERIORES<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5eabc7 elementor-pagination-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"d5eabc7\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;navigation&quot;:&quot;dots&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrusel d&#039;imatges\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_01-2.png\" alt=\"slider_01\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_07.png\" alt=\"slider_07\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_04.png\" alt=\"slider_04\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_03.png\" alt=\"slider_03\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 de 5\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/www.agrifoodporttarragona.com\/wp-content\/uploads\/2026\/02\/slider_02.png\" alt=\"slider_02\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b5cbde1 e-flex e-con-boxed e-con e-parent\" data-id=\"b5cbde1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-820533a elementor-widget elementor-widget-n-accordion\" data-id=\"820533a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:300,&quot;sizes&quot;:[]},&quot;max_items_expended&quot;:&quot;one&quot;}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-1360\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-1360\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Empresas participantes en ediciones anteriores <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-1360\" class=\"elementor-element elementor-element-9975dd1 e-con-full e-flex e-con e-child\" data-id=\"9975dd1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cfee088 elementor-widget elementor-widget-text-editor\" data-id=\"cfee088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>AACNI \u2022 AFFINITY PETCARE \u2022 AGEN. CIAL. AGROCESA, SL \u2022 AGENCIA CERESTOP, SL \u2022 AGRIFOOD ALTERNATIVE TECHNOLOGIES, SL \u2022 AGRO FUNDAMENTA, SL \u2022 AGROAESTIVUM \u2022 AGROCAT, SCCL \u2022 AGROCOM AGENTS, SL \u2022 AGROLAB-IBE\u0301RICA \u2022 AGROPRODUCCIONES OLEAGINOSAS \u2022 ALFASHIP \u2022 AROLA, ADUANAS Y CONSIGNACIONES, SL \u2022 ARS ALENDI \u2022 ASFAC\/QUALIMAC \u2022 ATLAS FORWARDING \u2022 AUTO CHARTERING \u2022 BASF ESPAN\u0303OLA, SL \u2022 BERGE\u0301 MARI\u0301TIMA, SL \u2022 BON\u00c0REA \u2022 BORGES AGRICULTURAL \u2022 BROKER CEREAL TARRACO \u2022 BUNGE IBE\u0301RICA, SAU \u2022 CARGILL, SLU \u2022 CEFETRA IBE\u0301RICA, SL \u2022 CEGECO \u2013 GRUP VALL COMPANYS \u2022 CEREALES Y HARINAS GARSAN \u2022 CHS INC. IBERIA \u2022 CINCAPORC \u2022 CME \u2022 COFCO INTERNATIONAL \u2022 CONSILIAGRA \u2022 CONTROL UNIO\u0301N \u2022 COOP. IVARS \u2022 COPIRAL \u2022 COTECNA \u2022 CUARTE, SA \u2022 DE HEUS \u2022 DNIPRO \u2022 CARGO LIMITED \u2022 E.F.F. \u2022 ERGRANSA \u2022 ERHARDT \u2022 ERSHIP \u2022 ETG COMMODITIES \u2022 EUROPORTS \u2022 FEFAC \u2022 FERTILIZANTES TARRAGONA, SL \u2022 FORRAJES SAN MATEO \u2022 FORO INTERALI- MENTARIO \u2022 FUNDACIO\u0301N FITSOS \u2022 GALLEY GULF CHARTERING \u2022 GAP, SL. (GESTORA PRODUCTOS AGROPECUARIOS) \u2022 GAVILON ESPAN\u0303A \u2022 GERMANS FARR\u00c9 \u2022 GESIURIS SGIIC, SA \u2022 GLENCORE \u2022 GRANJA CRUSVI, SA \u2022 GRUPO AN, S, COOP. \u2022 GRUPO JORGE \u2022 GRUPO NOGAR\/GALIGRAIN \u2022 GUINJOAN ORTEGA AG. CIAL \u2022 HARINERA DE SELGUA \u2022 HOWE ROBINSON PARTNERS \u2022 IACA \u2022INSPECTORATE ESPAN\u0303OLA \u2022 INTERTEK (AGRIWORLD) \u2022 INTL. FC STONE \u2022 IRTA \u2022 JANUS ALIMENTACIO\u0301 BUSINESS \u2022 KEMIN IBE\u0301RICA \u2022 L. CONCEPT, SL \u2022 LAG \u2022 LLOTJA DE CEREALS DE BARCELONA \u2022 LOUIS DREYFUS COMPANY ESPAN\u0303A, SA \u2022 MARI\u0301TIMA DEL MEDITERRANEO, SAU \u2022 MERCADONA \u2022 MIARNAU AGRITECNO \u2022 MTC COMMODITIES \u2022 NANTA \u2022 NEXT MARITIME \u2022 NOATUM TERMINAL TARRAGONA \u2022 OCA GLOBAL \u2022 ONUS LOGI\u0301STICA, SL \u2022 PANDA AGRICULTURE &amp; WATER FOUND \u2022 PIENSOS PROCASA \u2022 PIENSOS UNZUE\u0301 \u2022 PINSAGRO, SA \u2022 PORT SUR CASTELLO\u0301N, SA \u2022 QUIMIALMEL, SA \u2022 RIERA ROURA \u2022 SA, DAMM \u2022 SAMCA \/ TIM \u2022 SAIPOL \u2022 SANITRADE, SL \u2022 SAYBOLT \u2022 SGS \u2022 SILOS CORDOBA S.L.U \u2022 SUBMINISTRADORA DE CEREALS, SL \u2022 SUPERCONTROL &amp; MARITIME SERVICES \u2022 TESERCUS \u2022 TRANSMAR \u2022 TRILATERAL INC. \u2022 TROUW NUTRITION IBE\u0301RICA \u2022 U.S. SOYBEAN EXPORT COUNCIL \u2022 UNIVERSIDAD DE MADRID A DISTANCIA \u2022 UNIVERSIDAD DE VALENCIA \u2022 UNIVERSIDAD POLITE\u0301CNICA DE MADRID \u2022 UNIVERSITAT ROVIRA I VIRGILI \u2022 VAL DE GASCONE \/ BROKER ACOR \u2022 VALLE DE FISCAL, SA \u2022 VERTEX BIOENERGY \u2022 ZELENY INFORMACIO\u0301N Y MERCADO, SL \u2022 ZURRIOLA MARI\u0301TIMA, SLU<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Salutaci\u00f3n Una gran oportunidad para preparar el futuro compartiendo ideas y propuestas Port Tarragona presenta el 5th\u00a0Agrifood International Congress, que tendr\u00e1 lugar los d\u00edas 15 y 16 de octubre de 2026 y que, como en ediciones anteriores, pretende ser el foro de intercambio de conocimientos e informaci\u00f3n m\u00e1s importante del sector en el sur de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-390","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/pages\/390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/comments?post=390"}],"version-history":[{"count":40,"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/pages\/390\/revisions"}],"predecessor-version":[{"id":1078,"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/pages\/390\/revisions\/1078"}],"wp:attachment":[{"href":"https:\/\/www.agrifoodporttarragona.com\/es\/wp-json\/wp\/v2\/media?parent=390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}